{"id":99,"date":"2006-04-10T02:32:06","date_gmt":"2006-04-10T00:32:06","guid":{"rendered":"http:\/\/www.misterp.net\/words\/2006\/04\/hardware-galore\/"},"modified":"2006-04-10T02:32:06","modified_gmt":"2006-04-10T00:32:06","slug":"hardware-galore","status":"publish","type":"post","link":"https:\/\/www.misterp.net\/words\/2006\/04\/hardware-galore\/","title":{"rendered":"Hardware galore"},"content":{"rendered":"<p><P>Ca faisait quelque temps que la pompe de mon watercooling, qui tournait non stop depuis 3-4 ans, commen\u00e7ait \u00e0 faire un bruit bizarre.<\/P><P>Ca faisait \u00e9galement un bon moment que j&#8217;avais laiss\u00e9 tomber les jeux vid\u00e9os, car je n&#8217;ai pas pour habitude de racheter une carte graphique tous les ans, je suis plus un adepte du &#8220;on prend le top du moment, et on verra quand \u00e7a ne tiendra plus le coup&#8221;.<\/P><P>R\u00e9sultat des courses, un combo assez violent&nbsp;la semaine derni\u00e8re, pour le mat\u00e9riel, et le compte en banque \u00e0 l&#8217;occasion.<\/P><P><IMG src=\"\/words\/wp-content\/uploads\/oblivion_ss1.jpg\"><\/P><br \/>\n<!--more--><P>Reprenons dans l&#8217;ordre. Mercredi soir, exc\u00e9d\u00e9 par le bruit d\u00e9sagr\u00e9able de la b\u00eate, j&#8217;\u00e9teins le PC et coupe la pompe. Le lendemain, \u00e9videmment, elle ne d\u00e9marre plus. Enfin, elle ne pompe plus, plut\u00f4t. Deux alarmes temp\u00e9ratures plus tard, j&#8217;essaie de la remplacer par la nouvelle pompe re\u00e7ue la veille &#8211; j&#8217;avais bien fait de commander du matos watercooling quelques jours auparavant, pour le coup. Mais \u00e9videmment, le PC ne d\u00e9marre plus. Bon, je dois aller bosser, donc je laisse le bordel en plan ;&nbsp;et d\u00e9cide de passer \u00e0 Montgallet dans l&#8217;apr\u00e8s-midi pour effectuer la mise \u00e0 jour hardware qui trottait dans un coin de ma t\u00eate depuis&#8230; euh&#8230; avouons-le, depuis la sortie d&#8217;Oblivion.<\/P><P>R\u00e9sultat des courses :<\/P><UL><LI><STRONG>Athlon 64 X2 3800+<\/STRONG> (le 4400 est beaucoup trop cher avec ses 2Mo de cache, et le 4200 sans int\u00e9ret vu qu&#8217;on peut overclocker le 3800 \u00e0 l&#8217;identique sans aucun probl\u00e8me)<\/LI><LI><STRONG>ASUS A8N-Sli premium<\/STRONG> &#8211; ouais je reste fid\u00e8le \u00e0 ASUS, je sais pas pourquoi d&#8217;ailleurs, j&#8217;aime bien leur matos hi-end. La carte est passive, avec un heatpipe pour le chipset, on verra ce que \u00e7a donnera une fois le ventirad remplac\u00e9 par le waterblock&nbsp;NexXxoS XP que j&#8217;ai pr\u00e9vu&#8230;<\/LI><LI><STRONG>2Go<\/STRONG> (2x1Go) de (vraie) Samsung, j&#8217;arr\u00e8te PQI pour l&#8217;instant&#8230;<\/LI><LI>et le meilleur pour la fin, le monstre, une <STRONG>Sapphire Radeon X1900XT<\/STRONG>. Que j&#8217;ai d\u00e9j\u00e0 surnomm\u00e9e &#8220;le machin trop long&#8221; ou &#8220;la soufflerie&#8221;. Ouais, la super blague, \u00e0 force de faire des cartes de 30cm de long, bah je peux plus mettre le plateau avec les lecteurs\/graveurs DVD. Vais devoir jouer du Dremel. Pfff.<\/LI><\/UL><P>Cons\u00e9quence directe de la chose, notre petit serveur Duncan ador\u00e9 voit son Sempron 2500+ remplac\u00e9 par un Barton 3000+. Ca doit lui faire plaisir.<\/P><P>Autre cons\u00e9quence, apr\u00e8s avoir ram\u00e9 comme un gal\u00e8rien du jeudi 21h au vendredi 14h pour faire red\u00e9marrer la b\u00eate (je vous&nbsp;\u00e9pargne les d\u00e9tails, du genre pin d&#8217;un connecteur IDE enfonc\u00e9e&#8230;),&nbsp;bah maintenant je fais mumuse avec Morrowind &#8220;tout \u00e0 fond sa race&#8221;, et Oblivion depuis tout \u00e0 l&#8217;heure. En 1920&#215;1200. Et j&#8217;ai genre 30fps dans ce dernier. Et non, je n&#8217;ai pas honte.<\/P><P>Bon, certes, je vais encore manger des pates pendant un certain temps moi.<\/P><P>Ah et donc, prochaine \u00e9tape, dans la semaine probablement, mise en place du nouveau watercooling :<\/P><UL><LI>Eihem 1048<\/LI><LI>NexXxoS XP<\/LI><LI>3x 1A-HD2 de chez 1A-Cooling pour les disques durs. Ouais, faut vraiment que je vire le 4\u00e8me disque avant qu&#8217;il ne cr\u00e8ve, donc \u00e7a va m&#8217;inciter. Je ne pense pas que le refroidissement &#8220;par la tranche&#8221; soit super efficace, mais \u00e7a reste le syst\u00e8me le moins intrusif. Et bon,&nbsp;marre du ventilo 8cm d\u00e9di\u00e9 aux disques&#8230;<\/LI><LI>Un radiateur &#8220;Silent Lord&#8221; des m\u00eames 1A-Cooling. Un enorme machin de 40x40cm que j&#8217;ai judicieusement mis derri\u00e8re le 24&#8243;. Nickel.<\/LI><\/UL><P>On va voir ce que \u00e7a donne d\u00e9j\u00e0 avec le proc + les disques + la vieille CG PCI qui me sert pour le 2\u00e8me \u00e9cran (la 2\u00e8me sortie de la principale servant pour le projo). Si c&#8217;est pas trop mal, j&#8217;essayerai de watercooler la Radeon, au pire en rajoutant un 2\u00e8me radiateur actif optionnel pour refroidir en cas de grosse charge.<\/P><P>Bref, encore du fun en perspective&#8230;<\/P><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ca faisait quelque temps que la pompe de mon watercooling, qui tournait non stop depuis 3-4 ans, commen\u00e7ait \u00e0 faire un bruit bizarre. Ca faisait \u00e9galement un bon moment que j&#8217;avais laiss\u00e9 tomber les jeux vid\u00e9os, car je n&#8217;ai pas pour habitude de racheter une carte graphique tous les ans, je suis plus un adepte &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.misterp.net\/words\/2006\/04\/hardware-galore\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Hardware galore&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts\/99"}],"collection":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/comments?post=99"}],"version-history":[{"count":0,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts\/99\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/media?parent=99"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/categories?post=99"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/tags?post=99"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}