{"id":64,"date":"2004-04-20T16:20:00","date_gmt":"2004-04-20T14:20:00","guid":{"rendered":"http:\/\/www.misterp.net\/words\/2004\/04\/mysql-caching\/"},"modified":"2004-04-20T16:20:00","modified_gmt":"2004-04-20T14:20:00","slug":"mysql-caching","status":"publish","type":"post","link":"https:\/\/www.misterp.net\/words\/2004\/04\/mysql-caching\/","title":{"rendered":"MySQL caching"},"content":{"rendered":"<p>Juste histoire de dire que le site vit un peu, j&#8217;ai activ\u00e9 le cache MySQL, ce qui fait gagner quelques millisecondes sur la g\u00e9n\u00e9ration&#8230;<\/p>\n<p>A part \u00e7a oui oui je vais bosser sur ce site, promis \ud83d\ude09<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juste histoire de dire que le site vit un peu, j&#8217;ai activ\u00e9 le cache MySQL, ce qui fait gagner quelques millisecondes sur la g\u00e9n\u00e9ration&#8230; A part \u00e7a oui oui je vais bosser sur ce site, promis \ud83d\ude09<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts\/64"}],"collection":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/comments?post=64"}],"version-history":[{"count":0,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts\/64\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/media?parent=64"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/categories?post=64"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/tags?post=64"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}