{"id":46,"date":"2003-08-18T10:59:18","date_gmt":"2003-08-18T08:59:18","guid":{"rendered":"http:\/\/www.misterp.net\/words\/2003\/08\/return-of-ze-warlord\/"},"modified":"2003-08-18T10:59:18","modified_gmt":"2003-08-18T08:59:18","slug":"return-of-ze-warlord","status":"publish","type":"post","link":"https:\/\/www.misterp.net\/words\/2003\/08\/return-of-ze-warlord\/","title":{"rendered":"Return of ze Warlord"},"content":{"rendered":"<p><i>(oui je sais j&#8217;ai de plus en plus de mal pour les titres, cherchez pas)<\/i><br \/>\nJuste pour dire que la webcam \u00e9tait de nouveau op\u00e9rationnelle. Voil\u00e0 voil\u00e0. Et sinon, beau temps chez vous ?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(oui je sais j&#8217;ai de plus en plus de mal pour les titres, cherchez pas) Juste pour dire que la webcam \u00e9tait de nouveau op\u00e9rationnelle. Voil\u00e0 voil\u00e0. Et sinon, beau temps chez vous ?<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts\/46"}],"collection":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/comments?post=46"}],"version-history":[{"count":0,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts\/46\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/media?parent=46"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/categories?post=46"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/tags?post=46"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}