{"id":306,"date":"2013-11-15T16:41:00","date_gmt":"2013-11-15T15:41:00","guid":{"rendered":"http:\/\/www.misterp.net\/words\/2013\/11\/ma-next-gen\/"},"modified":"2020-07-23T08:44:16","modified_gmt":"2020-07-23T06:44:16","slug":"ma-next-gen","status":"publish","type":"post","link":"https:\/\/www.misterp.net\/words\/2013\/11\/ma-next-gen\/","title":{"rendered":"Ma next-gen"},"content":{"rendered":"<p>Pendant que tous se paluchent sur les Xboxstation 41, dont je me tamponne totalement (vu que je joue sur PC je le rappelle), j&#8217;ai investi des sous que Microsoft et Sony n&#8217;auront pas pour ma peut-\u00eatre reconversion apr\u00e8s Gameblog. Voici donc ce qui est arriv\u00e9 chez moi cette semaine !<\/p>\n<p><a href=\"https:\/\/www.misterp.net\/words\/wp-content\/uploads\/168714.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" src=\"https:\/\/www.misterp.net\/words\/wp-content\/uploads\/168714_med.jpg\" alt=\"\"><\/a><\/p>\n<p>Cette objet est un bouzouki irlandais. Un instrument totalement batard (vu que le bouzouki est grec, \u00e0 la base, rappelons-le), arriv\u00e9 dans les ann\u00e9es 60 en Angleterre et modifi\u00e9 pour s&#8217;adapter \u00e0 de la musique traditionnelle locale.<\/p>\n<p>Accessoirement, \u00e7a ressemble aussi pas mal \u00e0 un cistre, et du coup, \u00e7a sert aussi \u00e0 faire de la musique m\u00e9di\u00e9vale (le grand public aura pu voir Luc Arbogast en utiliser un, et moi faire mon hipster vu que j&#8217;avais d\u00e9j\u00e0 fait de la promo du monsieur avant qu&#8217;il ne soit connu, paf)<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/9J7KRfD1FF0\" width=\"640\" height=\"360\" frameborder=\"0\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pendant que tous se paluchent sur les Xboxstation 41, dont je me tamponne totalement (vu que je joue sur PC je le rappelle), j&#8217;ai investi des sous que Microsoft et Sony n&#8217;auront pas pour ma peut-\u00eatre reconversion apr\u00e8s Gameblog. Voici donc ce qui est arriv\u00e9 chez moi cette semaine ! Cette objet est un bouzouki &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.misterp.net\/words\/2013\/11\/ma-next-gen\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Ma next-gen&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"_links":{"self":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts\/306"}],"collection":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/comments?post=306"}],"version-history":[{"count":3,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts\/306\/revisions"}],"predecessor-version":[{"id":949,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts\/306\/revisions\/949"}],"wp:attachment":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/media?parent=306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/categories?post=306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/tags?post=306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}