{"id":239,"date":"2010-05-31T08:20:00","date_gmt":"2010-05-31T06:20:00","guid":{"rendered":"http:\/\/www.misterp.net\/words\/2010\/05\/un-batteur-qui-sait-soccuper\/"},"modified":"2010-05-31T08:20:00","modified_gmt":"2010-05-31T06:20:00","slug":"un-batteur-qui-sait-soccuper","status":"publish","type":"post","link":"https:\/\/www.misterp.net\/words\/2010\/05\/un-batteur-qui-sait-soccuper\/","title":{"rendered":"Un batteur qui sait s&#8217;occuper"},"content":{"rendered":"<p>Vu comme \u00e7a, il n&#8217;y a rien de bien particulier dans ce petit groupe qui reprend ZZ Top. A part peut-\u00eatre les vestes jaunes. Ou alors, le <strong>style tr\u00e8s particulier du batteur<\/strong> ?<\/p>\n<p style=\"text-align: center;\">\n<object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" width=\"480\" height=\"385\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/6DVbt5W-DNc&amp;hl=fr_FR&amp;fs=1&amp;\" \/><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowScriptAccess\" value=\"always\" \/><embed type=\"application\/x-shockwave-flash\" width=\"480\" height=\"385\" src=\"http:\/\/www.youtube.com\/v\/6DVbt5W-DNc&amp;hl=fr_FR&amp;fs=1&amp;\" allowscriptaccess=\"always\" allowfullscreen=\"true\"><\/embed><\/object>\n<\/p>\n<p style=\"text-align: center;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vu comme \u00e7a, il n&#8217;y a rien de bien particulier dans ce petit groupe qui reprend ZZ Top. A part peut-\u00eatre les vestes jaunes. Ou alors, le style tr\u00e8s particulier du batteur ? \u00a0<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts\/239"}],"collection":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/comments?post=239"}],"version-history":[{"count":0,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts\/239\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/media?parent=239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/categories?post=239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/tags?post=239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}