{"id":135,"date":"2007-12-22T01:24:55","date_gmt":"2007-12-22T00:24:55","guid":{"rendered":"http:\/\/www.misterp.net\/words\/2007\/12\/nouvelle-skin-viteuf\/"},"modified":"2007-12-22T01:24:55","modified_gmt":"2007-12-22T00:24:55","slug":"nouvelle-skin-viteuf","status":"publish","type":"post","link":"https:\/\/www.misterp.net\/words\/2007\/12\/nouvelle-skin-viteuf\/","title":{"rendered":"Nouvelle skin viteuf&#8217;"},"content":{"rendered":"<p><P>Et m\u00eame pas sp\u00e9ciale No\u00ebl ou quoi ou qu&#8217;est-ce, juste parce que j&#8217;en avais un peu marre du fond bleu en plaques.<\/P><P>Bon oui je sais, c&#8217;est un peu triste la. Mais c&#8217;est sobre. Et sobre is good.<\/P><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Et m\u00eame pas sp\u00e9ciale No\u00ebl ou quoi ou qu&#8217;est-ce, juste parce que j&#8217;en avais un peu marre du fond bleu en plaques.Bon oui je sais, c&#8217;est un peu triste la. Mais c&#8217;est sobre. Et sobre is good.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts\/135"}],"collection":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/comments?post=135"}],"version-history":[{"count":0,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts\/135\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/media?parent=135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/categories?post=135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/tags?post=135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}