{"id":12,"date":"2002-06-01T15:32:29","date_gmt":"2002-06-01T13:32:29","guid":{"rendered":"http:\/\/www.misterp.net\/words\/2002\/06\/bon-jai-rien-poste-en-home-depuis-des-lustres\/"},"modified":"2002-06-01T15:32:29","modified_gmt":"2002-06-01T13:32:29","slug":"bon-jai-rien-poste-en-home-depuis-des-lustres","status":"publish","type":"post","link":"https:\/\/www.misterp.net\/words\/2002\/06\/bon-jai-rien-poste-en-home-depuis-des-lustres\/","title":{"rendered":"Bon j&#8217;ai rien post\u00e9 en home depuis des lustres&#8230;"},"content":{"rendered":"<p>Mais c&#8217;est parce que je d\u00e9veloppais des trucs et que je les testais dans des zones priv\u00e9es.<br \/>\n<!--more-->Donc en vrac, upload de fichiers dans les news, g\u00e9n\u00e9ration de thumbnails automatique avec lien popup, tout \u00e7a tout \u00e7a, et la partie admin qui progresse.<br \/>\nYoupi.<\/p>\n<p>Et tout \u00e7a ne sert \u00e0 RIEN vu que mon IIS plantouille d\u00e8s que plus de quelques personnes se connectent en m\u00eame temps =^)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mais c&#8217;est parce que je d\u00e9veloppais des trucs et que je les testais dans des zones priv\u00e9es.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts\/12"}],"collection":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/comments?post=12"}],"version-history":[{"count":0,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts\/12\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/media?parent=12"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/categories?post=12"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/tags?post=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}