{"id":100,"date":"2006-05-08T16:19:08","date_gmt":"2006-05-08T14:19:08","guid":{"rendered":"http:\/\/www.misterp.net\/words\/2006\/05\/bon-ben-connected-4-alors\/"},"modified":"2006-05-08T16:19:08","modified_gmt":"2006-05-08T14:19:08","slug":"bon-ben-connected-4-alors","status":"publish","type":"post","link":"https:\/\/www.misterp.net\/words\/2006\/05\/bon-ben-connected-4-alors\/","title":{"rendered":"Bon ben Connected 4 alors"},"content":{"rendered":"<p><P>Avec mes installations de machine et le boulot en ce moment, pas&nbsp;le temps de raconter grand chose.<\/P><P>Rappelons&nbsp;donc&nbsp;juste que samedi, c&#8217;\u00e9tait la <A href=\"http:\/\/www.connected-parties.com\/dotclear\/\" target=_blank>Connected 4<\/A>, et que apr\u00e8s un pique-nique en for\u00eat <STRONG>humide<\/STRONG> (mais il pleut toujours, pendant les pique-niques), c&#8217;\u00e9tait une soir\u00e9e assez sympathique malgr\u00e9 la fatigue. On notera un concours de <A href=\"http:\/\/www.gunthernet.com\/\" target=_blank>G\u00fcnther<\/A> du plus bel effet. Et pour changer, je mets une photo de notre <A href=\"http:\/\/www.faskil.com\/\" target=_blank>DJ belge ador\u00e9<\/A>&nbsp;qui est en ce moment m\u00eame&nbsp;\u00e0 L.A, le pauvre.<\/P><P><IMG src=\"\/words\/wp-content\/uploads\/faskil_glasses.jpg\"><\/P><P><A href=\"http:\/\/60gp.ovh.net\/~vincentg\/Cafzone\/Connected%204\/\" target=_blank>Quelques photos par l\u00e0<\/A>.<\/P><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec mes installations de machine et le boulot en ce moment, pas&nbsp;le temps de raconter grand chose.Rappelons&nbsp;donc&nbsp;juste que samedi, c&#8217;\u00e9tait la Connected 4, et que apr\u00e8s un pique-nique en for\u00eat humide (mais il pleut toujours, pendant les pique-niques), c&#8217;\u00e9tait une soir\u00e9e assez sympathique malgr\u00e9 la fatigue. On notera un concours de G\u00fcnther du plus bel &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.misterp.net\/words\/2006\/05\/bon-ben-connected-4-alors\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Bon ben Connected 4 alors&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts\/100"}],"collection":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/comments?post=100"}],"version-history":[{"count":0,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/posts\/100\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/media?parent=100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/categories?post=100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.misterp.net\/words\/wp-json\/wp\/v2\/tags?post=100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}